{"id":12469,"date":"2023-11-23T19:54:35","date_gmt":"2023-11-23T18:54:35","guid":{"rendered":"https:\/\/sports-cards.nl\/product\/2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition\/"},"modified":"2026-04-11T23:55:41","modified_gmt":"2026-04-11T21:55:41","slug":"2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition","status":"publish","type":"product","link":"https:\/\/sports-cards.nl\/nl\/product\/2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition\/","title":{"rendered":"2022 Ronald Acuna Jr. #58 Topps Bowman Chrome Sapphire Refractor Edition"},"content":{"rendered":"<ul>\n<li>\u00a0Player: Ronald Acuna Jr.<\/li>\n<li>\u00a0Set: Topps Bowman Chrome<\/li>\n<li>\u00a0Team: Atlanta Braves<\/li>\n<li>\u00a0League: MLB<\/li>\n<li>\u00a0Year: 2022<\/li>\n<li>\u00a0Features: Single &#8211; Base &#8211; Sapphire Edition Refractor<\/li>\n<li>\u00a0Grade: Raw Near Mint\/Mint<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ronald Acuna Jr. &#8211; Atlanta Braves<\/p>\n","protected":false},"featured_media":12470,"template":"","meta":{"googlesitekit_rrm_CAowi9S-DA:productID":""},"product_brand":[],"product_cat":[3513,1221],"product_tag":[1403,1401,1568],"class_list":["post-12469","product","type-product","status-publish","has-post-thumbnail","product_cat-mlb-1990-2025-nl","product_cat-mlb-baseball-category-nl","product_tag-atlanta-braves-nl","product_tag-refractor-nl","product_tag-ronald-acuna-jr-nl","product_shipping_class-cards-nl","first","outofstock","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>2022 Ronald Acuna Jr. #58 Topps Bowman Chrome Sapphire Refractor Edition<\/title>\n<meta name=\"description\" content=\"Ronald Acuna Jr. - Atlanta Braves - 2022 Ronald Acuna Jr. #58 Topps Bowman Chrome Sapphire Refractor Edition\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sports-cards.nl\/nl\/product\/2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2022 Ronald Acuna Jr. #58 Topps Bowman Chrome Sapphire Refractor Edition\" \/>\n<meta property=\"og:description\" content=\"Ronald Acuna Jr. - Atlanta Braves - 2022 Ronald Acuna Jr. #58 Topps Bowman Chrome Sapphire Refractor Edition\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sports-cards.nl\/nl\/product\/2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition\/\" \/>\n<meta property=\"og:site_name\" content=\"Sports Cards NL\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sportscardsnl\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-11T21:55:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sports-cards.nl\/wp-content\/uploads\/2023\/11\/0002581_2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prijs\" \/>\n\t<meta name=\"twitter:data1\" content=\"&#036;4.79\" \/>\n\t<meta name=\"twitter:label2\" content=\"Beschikbaarheid\" \/>\n\t<meta name=\"twitter:data2\" content=\"Uitverkocht\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sports-cards.nl\\\/nl\\\/product\\\/2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition\\\/\",\"url\":\"https:\\\/\\\/sports-cards.nl\\\/nl\\\/product\\\/2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition\\\/\",\"name\":\"2022 Ronald Acuna Jr. #58 Topps Bowman Chrome Sapphire Refractor Edition\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sports-cards.nl\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sports-cards.nl\\\/nl\\\/product\\\/2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sports-cards.nl\\\/nl\\\/product\\\/2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sports-cards.nl\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/0002581_2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition-1.webp\",\"datePublished\":\"2023-11-23T18:54:35+00:00\",\"dateModified\":\"2026-04-11T21:55:41+00:00\",\"description\":\"Ronald Acuna Jr. - Atlanta Braves - 2022 Ronald Acuna Jr. #58 Topps Bowman Chrome Sapphire Refractor Edition\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sports-cards.nl\\\/nl\\\/product\\\/2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sports-cards.nl\\\/nl\\\/product\\\/2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/sports-cards.nl\\\/nl\\\/product\\\/2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sports-cards.nl\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/0002581_2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition-1.webp\",\"contentUrl\":\"https:\\\/\\\/sports-cards.nl\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/0002581_2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition-1.webp\",\"width\":1200,\"height\":1400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sports-cards.nl\\\/nl\\\/product\\\/2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sports-cards.nl\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sportkaarten webwinkel\",\"item\":\"https:\\\/\\\/sports-cards.nl\\\/nl\\\/winkel\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"2022 Ronald Acuna Jr. #58 Topps Bowman Chrome Sapphire Refractor Edition\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sports-cards.nl\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/sports-cards.nl\\\/nl\\\/\",\"name\":\"Sports Cards NL\",\"description\":\"Verzamelkaarten uit de NBA basketball \\\/ NHL hockey \\\/ NFL football \\\/ MLB baseball \\\/ Formule 1 \\\/ Voetbal \\\/ POP! \\\/ WWE  \\\/ Marvel \\\/ UFC \\\/ Racing \\\/ Pop culture \\\/ TCG  &amp; Packs \\\/ Boxes \\\/ Supplies \\\/ Jerseys \\\/ Boardgames &amp; More\",\"publisher\":{\"@id\":\"https:\\\/\\\/sports-cards.nl\\\/nl\\\/#organization\"},\"alternateName\":\"sports-cards.nl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sports-cards.nl\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sports-cards.nl\\\/nl\\\/#organization\",\"name\":\"Sports Cards NL\",\"alternateName\":\"sports-cards.nl\",\"url\":\"https:\\\/\\\/sports-cards.nl\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/sports-cards.nl\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sports-cards.nl\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Sports-Cards-NL-Logo-500-square.webp\",\"contentUrl\":\"https:\\\/\\\/sports-cards.nl\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Sports-Cards-NL-Logo-500-square.webp\",\"width\":500,\"height\":500,\"caption\":\"Sports Cards NL\"},\"image\":{\"@id\":\"https:\\\/\\\/sports-cards.nl\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sportscardsnl\",\"https:\\\/\\\/www.instagram.com\\\/sports_cards_nl\\\/\",\"https:\\\/\\\/nl.pinterest.com\\\/sportscardsnetherlandsnl\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@sports.cards.netherlands\"],\"ownershipFundingInfo\":\"https:\\\/\\\/sports-cards.nl\\\/about-sports-cards-nl\\\/\"}]}<\/script>\n<meta property=\"product:brand\" content=\"Topps\" \/>\n<meta property=\"product:price:amount\" content=\"4.79\" \/>\n<meta property=\"product:price:currency\" content=\"USD\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"Ronald Acuna Jr. - Atlanta Braves - Card #58\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"2022 Ronald Acuna Jr. #58 Topps Bowman Chrome Sapphire Refractor Edition","description":"Ronald Acuna Jr. - Atlanta Braves - 2022 Ronald Acuna Jr. #58 Topps Bowman Chrome Sapphire Refractor Edition","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sports-cards.nl\/nl\/product\/2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition\/","og_locale":"nl_NL","og_type":"article","og_title":"2022 Ronald Acuna Jr. #58 Topps Bowman Chrome Sapphire Refractor Edition","og_description":"Ronald Acuna Jr. - Atlanta Braves - 2022 Ronald Acuna Jr. #58 Topps Bowman Chrome Sapphire Refractor Edition","og_url":"https:\/\/sports-cards.nl\/nl\/product\/2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition\/","og_site_name":"Sports Cards NL","article_publisher":"https:\/\/www.facebook.com\/sportscardsnl","article_modified_time":"2026-04-11T21:55:41+00:00","og_image":[{"width":1200,"height":1400,"url":"https:\/\/sports-cards.nl\/wp-content\/uploads\/2023\/11\/0002581_2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Prijs":"&#36;4.79","Beschikbaarheid":"Uitverkocht"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sports-cards.nl\/nl\/product\/2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition\/","url":"https:\/\/sports-cards.nl\/nl\/product\/2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition\/","name":"2022 Ronald Acuna Jr. #58 Topps Bowman Chrome Sapphire Refractor Edition","isPartOf":{"@id":"https:\/\/sports-cards.nl\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sports-cards.nl\/nl\/product\/2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition\/#primaryimage"},"image":{"@id":"https:\/\/sports-cards.nl\/nl\/product\/2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition\/#primaryimage"},"thumbnailUrl":"https:\/\/sports-cards.nl\/wp-content\/uploads\/2023\/11\/0002581_2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition-1.webp","datePublished":"2023-11-23T18:54:35+00:00","dateModified":"2026-04-11T21:55:41+00:00","description":"Ronald Acuna Jr. - Atlanta Braves - 2022 Ronald Acuna Jr. #58 Topps Bowman Chrome Sapphire Refractor Edition","breadcrumb":{"@id":"https:\/\/sports-cards.nl\/nl\/product\/2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sports-cards.nl\/nl\/product\/2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/sports-cards.nl\/nl\/product\/2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition\/#primaryimage","url":"https:\/\/sports-cards.nl\/wp-content\/uploads\/2023\/11\/0002581_2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition-1.webp","contentUrl":"https:\/\/sports-cards.nl\/wp-content\/uploads\/2023\/11\/0002581_2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition-1.webp","width":1200,"height":1400},{"@type":"BreadcrumbList","@id":"https:\/\/sports-cards.nl\/nl\/product\/2022-ronald-acuna-jr-58-topps-bowman-chrome-sapphire-edition\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sports-cards.nl\/nl\/"},{"@type":"ListItem","position":2,"name":"Sportkaarten webwinkel","item":"https:\/\/sports-cards.nl\/nl\/winkel\/"},{"@type":"ListItem","position":3,"name":"2022 Ronald Acuna Jr. #58 Topps Bowman Chrome Sapphire Refractor Edition"}]},{"@type":"WebSite","@id":"https:\/\/sports-cards.nl\/nl\/#website","url":"https:\/\/sports-cards.nl\/nl\/","name":"Sports Cards NL","description":"Verzamelkaarten uit de NBA basketball \/ NHL hockey \/ NFL football \/ MLB baseball \/ Formule 1 \/ Voetbal \/ POP! \/ WWE  \/ Marvel \/ UFC \/ Racing \/ Pop culture \/ TCG  &amp; Packs \/ Boxes \/ Supplies \/ Jerseys \/ Boardgames &amp; More","publisher":{"@id":"https:\/\/sports-cards.nl\/nl\/#organization"},"alternateName":"sports-cards.nl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sports-cards.nl\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/sports-cards.nl\/nl\/#organization","name":"Sports Cards NL","alternateName":"sports-cards.nl","url":"https:\/\/sports-cards.nl\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/sports-cards.nl\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/sports-cards.nl\/wp-content\/uploads\/2025\/07\/Sports-Cards-NL-Logo-500-square.webp","contentUrl":"https:\/\/sports-cards.nl\/wp-content\/uploads\/2025\/07\/Sports-Cards-NL-Logo-500-square.webp","width":500,"height":500,"caption":"Sports Cards NL"},"image":{"@id":"https:\/\/sports-cards.nl\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sportscardsnl","https:\/\/www.instagram.com\/sports_cards_nl\/","https:\/\/nl.pinterest.com\/sportscardsnetherlandsnl\/","https:\/\/www.youtube.com\/@sports.cards.netherlands"],"ownershipFundingInfo":"https:\/\/sports-cards.nl\/about-sports-cards-nl\/"}]},"product_brand":"Topps","product_price_amount":"4.79","product_price_currency":"USD","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"Ronald Acuna Jr. - Atlanta Braves - Card #58","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/sports-cards.nl\/nl\/wp-json\/wp\/v2\/product\/12469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sports-cards.nl\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sports-cards.nl\/nl\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sports-cards.nl\/nl\/wp-json\/wp\/v2\/media\/12470"}],"wp:attachment":[{"href":"https:\/\/sports-cards.nl\/nl\/wp-json\/wp\/v2\/media?parent=12469"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sports-cards.nl\/nl\/wp-json\/wp\/v2\/product_brand?post=12469"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sports-cards.nl\/nl\/wp-json\/wp\/v2\/product_cat?post=12469"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sports-cards.nl\/nl\/wp-json\/wp\/v2\/product_tag?post=12469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}